{"id":608,"count":1,"description":"","link":"https:\/\/www.musictravel.com\/blog\/tag\/international-performance-tour\/","name":"international performance tour","slug":"international-performance-tour","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>international performance tour Archives - Music Travel Consultants<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.musictravel.com\/blog\/tag\/international-performance-tour\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"international performance tour Archives - Music Travel Consultants\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.musictravel.com\/blog\/tag\/international-performance-tour\/\" \/>\n<meta property=\"og:site_name\" content=\"Music Travel Consultants\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.musictravel.com\/blog\/wp-content\/uploads\/2017\/07\/logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@musictravel1\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.musictravel.com\\\/blog\\\/tag\\\/international-performance-tour\\\/\",\"url\":\"https:\\\/\\\/www.musictravel.com\\\/blog\\\/tag\\\/international-performance-tour\\\/\",\"name\":\"international performance tour Archives - Music Travel Consultants\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.musictravel.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.musictravel.com\\\/blog\\\/tag\\\/international-performance-tour\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.musictravel.com\\\/blog\\\/tag\\\/international-performance-tour\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.musictravel.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"international performance tour\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.musictravel.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.musictravel.com\\\/blog\\\/\",\"name\":\"Music Travel Consultants\",\"description\":\"Travel Planners for Performance Groups\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.musictravel.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.musictravel.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.musictravel.com\\\/blog\\\/#organization\",\"name\":\"Music Travel Consultants\",\"url\":\"https:\\\/\\\/www.musictravel.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.musictravel.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.musictravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/mtclogo375x244.png\",\"contentUrl\":\"https:\\\/\\\/www.musictravel.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/mtclogo375x244.png\",\"width\":375,\"height\":244,\"caption\":\"Music Travel Consultants\"},\"image\":{\"@id\":\"https:\\\/\\\/www.musictravel.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/musictravelconsultants\\\/\",\"https:\\\/\\\/x.com\\\/musictravel1\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/music-travel-consultants?trk=extra_biz_viewers_viewed\",\"http:\\\/\\\/www.youtube.com\\\/channel\\\/UC8exNAeHw-Luyeo8PeXFNfg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"international performance tour Archives - Music Travel Consultants","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.musictravel.com\/blog\/tag\/international-performance-tour\/","og_locale":"en_US","og_type":"article","og_title":"international performance tour Archives - Music Travel Consultants","og_url":"https:\/\/www.musictravel.com\/blog\/tag\/international-performance-tour\/","og_site_name":"Music Travel Consultants","og_image":[{"width":1140,"height":445,"url":"https:\/\/www.musictravel.com\/blog\/wp-content\/uploads\/2017\/07\/logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@musictravel1","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.musictravel.com\/blog\/tag\/international-performance-tour\/","url":"https:\/\/www.musictravel.com\/blog\/tag\/international-performance-tour\/","name":"international performance tour Archives - Music Travel Consultants","isPartOf":{"@id":"https:\/\/www.musictravel.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.musictravel.com\/blog\/tag\/international-performance-tour\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.musictravel.com\/blog\/tag\/international-performance-tour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.musictravel.com\/blog\/"},{"@type":"ListItem","position":2,"name":"international performance tour"}]},{"@type":"WebSite","@id":"https:\/\/www.musictravel.com\/blog\/#website","url":"https:\/\/www.musictravel.com\/blog\/","name":"Music Travel Consultants","description":"Travel Planners for Performance Groups","publisher":{"@id":"https:\/\/www.musictravel.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.musictravel.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.musictravel.com\/blog\/#organization","name":"Music Travel Consultants","url":"https:\/\/www.musictravel.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.musictravel.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.musictravel.com\/blog\/wp-content\/uploads\/2022\/06\/mtclogo375x244.png","contentUrl":"https:\/\/www.musictravel.com\/blog\/wp-content\/uploads\/2022\/06\/mtclogo375x244.png","width":375,"height":244,"caption":"Music Travel Consultants"},"image":{"@id":"https:\/\/www.musictravel.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/musictravelconsultants\/","https:\/\/x.com\/musictravel1","https:\/\/www.linkedin.com\/company\/music-travel-consultants?trk=extra_biz_viewers_viewed","http:\/\/www.youtube.com\/channel\/UC8exNAeHw-Luyeo8PeXFNfg"]}]}},"_links":{"self":[{"href":"https:\/\/www.musictravel.com\/blog\/wp-json\/wp\/v2\/tags\/608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.musictravel.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.musictravel.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.musictravel.com\/blog\/wp-json\/wp\/v2\/posts?tags=608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}